{"id":6621,"date":"2017-08-29T22:12:58","date_gmt":"2017-08-29T20:12:58","guid":{"rendered":"http:\/\/www.trading-ideen.de\/wordpress\/?p=6621"},"modified":"2022-07-20T16:58:22","modified_gmt":"2022-07-20T14:58:22","slug":"volumentrend","status":"publish","type":"post","link":"https:\/\/www.trading-ideen.de\/wordpress\/volumentrend\/","title":{"rendered":"Ausbr\u00fcche mit dem Volumentrend handeln"},"content":{"rendered":"<p><strong>Der Volumentrend zeigt, ob ein Kurstrend gesund ist.<\/strong> Beide Trendvarianten m\u00fcssen im Einklang sein. Nur dann wird ein Trend von Dauer sein. Achten Sie deshalb auf den Volumentrend und Ihre Gewinne werden sich ausweiten.<\/p>\n<p>Vermutlich k\u00f6nnen viele B\u00f6rsianer mit dem Begriff \u201eVolumentrend\u201c nichts anfangen. Im Wesentlichen geht es um die Kursbewegung und das entsprechend aufgewendete Volumen. Das Handelsvolumen entspricht im \u00fcbertragenden Sinn, dem Kraftaufwand, um den Kurs nach oben oder unten zu bewegen.<\/p>\n<p><strong>Mit der Analyse des Volumentrends ist es m\u00f6glich, die Qualit\u00e4t des Kurstrends zu \u00fcberpr\u00fcfen.<\/strong><\/p>\n<p>Jeder Aufw\u00e4rtstrend wird angetrieben durch einen \u00dcberhang von Kaufwilligen, die kontinuierlich h\u00f6here Kurse akzeptieren. Umgekehrt, im Falle eines Abw\u00e4rtstrends, sind es die verkaufswilligen Marktteilnehmer, die sich mehrheitlich zum Verkaufen gezwungen f\u00fchlen.<\/p>\n<p>Der Markt bewegt sich innerhalb eines Trends in rhythmischen Bewegungen. Das Ergebnis eines Aufw\u00e4rtstrends sind geh\u00e4ufte neue Hochs und h\u00f6heres Tiefs.<\/p>\n<p><a href=\"https:\/\/www.trading-ideen.de\/wordpress\/wp-content\/uploads\/2017\/08\/b1.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-6622\" src=\"https:\/\/www.trading-ideen.de\/wordpress\/wp-content\/uploads\/2017\/08\/b1-600x544.png\" alt=\"\" width=\"358\" height=\"325\" srcset=\"https:\/\/www.trading-ideen.de\/wordpress\/wp-content\/uploads\/2017\/08\/b1-600x544.png 600w, https:\/\/www.trading-ideen.de\/wordpress\/wp-content\/uploads\/2017\/08\/b1.png 648w\" sizes=\"auto, (max-width: 358px) 100vw, 358px\" \/><\/a><\/p>\n<p><em>Bild: Theorie des Trends innerhalb der Markttechnik<\/em><\/p>\n<p>Das obere Bild zeigt den Trendkanal eines Aufw\u00e4rtstrends. Beim Volumentrend geht es um die gleichen Wellenbewegungen, lediglich mit dem Unterschied, dass das Handelsvolumen im Fokus steht. Wenn Kurstrend und Volumentrend die gleichen Muster zeigen, dann wird der Trend sich dauerhaft fortsetzen.<\/p>\n<h3>So funktioniert der Volumentrend<\/h3>\n<p>Weil die pure Zahl des Handelsvolumens nat\u00fcrlich keine Richtung angeben kann, m\u00fcssen wir f\u00fcr eine Analyse die Verbindung zum Kurs herstellen. Die einfachste und bekannteste L\u00f6sung bietet der On-Balance-Volume-Indikator (OBV). Das Handelsvolumen wird beim OBV grunds\u00e4tzlich kumuliert. Aufaddiert wird es, wenn der Schlusskurs h\u00f6her liegt als bei der Candlestick zuvor. Passend dazu wird das Volumen subtrahiert, wenn der aktuelle Schlusskurs niedriger liegt. Ein einfaches, aber wirkungsvolles Prinzip, um Kurs und Volumen zu verkn\u00fcpfen.<\/p>\n<p>Der OBV ist ein relativ alter Indikator aus den 1960er-Jahren. Die Jahrzehnte haben allerdings nichts an der Indikatorwirksamkeit einb\u00fc\u00dfen lassen. Er ist immer noch so effektiv, wie am ersten Tag.<\/p>\n<p><a href=\"https:\/\/www.trading-ideen.de\/wordpress\/wp-content\/uploads\/2017\/08\/b2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-6623\" src=\"https:\/\/www.trading-ideen.de\/wordpress\/wp-content\/uploads\/2017\/08\/b2.jpg\" alt=\"\" width=\"442\" height=\"289\" \/><\/a><\/p>\n<p><em>Bild: Im Aufw\u00e4rtstrend sollten die Wellen in der Aufw\u00e4rtsbewegung erh\u00f6htes Volumen besitzen<\/em><\/p>\n<h3>Wie hoch darf das Volumen sein?<\/h3>\n<p>Wenn von einem \u00fcberdurchschnittlichen Volumen gesprochen wird, dann darf dies nicht wie ein Gesetz angesehen werden. Das Handelsvolumen steht in enger Beziehung mit den Emotionen der Marktteilnehmer. Kann man in einem Kursverlauf durchschnittlich mehr Volumen in der Aufw\u00e4rtsrichtung vorzufinden, deutet das auf reges Kaufinteresse hin. Ist jedoch das Volumen schw\u00e4cher, muss es nicht zwingend zu einem Trendende kommen. Zu einem schw\u00e4cheren Handelsvolumen kommt es auch, wenn der Markt unsicher ist, oder wenn wichtige Wirtschaftsnachrichten zu erwarten sind. Unsicherheit f\u00fchrt in der Regel nicht zur Umkehr, sondern zu \u201ewirren\u201c Handlungen der Marktteilnehmer. Technische Fehlsignale sind in unsicheren Zeiten nicht ungew\u00f6hnlich. Sobald sich die Lage aber beruhigt hat, setzt der Markt den Trend wieder fort.<\/p>\n<p>Vereinfacht ausgedr\u00fcckt k\u00f6nnte man sagen, dass eine Kurswelle sich fortsetzt, wenn die H\u00f6he des Handelsvolumens \u00fcberdurchschnittlich ist. Allerdings ist ein extrem hohes Handelsvolumen f\u00fcr einen Trend nicht f\u00f6rderlich. Volumenspitzen enthalten n\u00e4mlich den Charakterzug einer kurzfristigen Ersch\u00f6pfung. Nicht selten stoppt deshalb eine Bewegung mit Volumenspitze. Es tritt anschlie\u00dfend eine Pause ein, bei der sich die Marktteilnehmer sich neu orientieren.<\/p>\n<h3>Vorteile mit dem Volumentrend<\/h3>\n<p>Die Arbeit mit der Volumen-Analyse muss sich lohnen. Wenn man die Kraft einer Kursbewegung absch\u00e4tzt, dann sollte das auch im praktischen Trading einen Vorteil ergeben. So ein Vorteil w\u00e4re zum Beispiel, dass ein gesunder Volumentrend leichter Widerst\u00e4nde im Aufw\u00e4rtstrend bricht. Ein Trend l\u00e4uft schlie\u00dflich nicht wie eine gerade Linie. Auf- und Abbewegungen folgen einem eigenen zyklischen Rhythmus. Nicht un\u00fcblich sind drei gro\u00dfe Schritte vor und zwei kleine zur\u00fcck. Innerhalb eines Aufw\u00e4rtstrends ergibt das ein regelm\u00e4\u00dfiges neues Hoch. Passend dazu geh\u00f6rt jeweils ein neuer Ausbruch \u00fcber das vorherige Hoch. Und wenn Kurstrend und Volumentrend in Harmonie sind, dann gelingen die Ausbr\u00fcche besonders leicht.<\/p>\n<h3>Der Volumentrend harmoniert mit der Fundamentalanalyse<\/h3>\n<p>William F. Eng ver\u00f6ffentliche 1988 in seinem Buch \u201eTechnical Analysis of Stocks, Options and Futures\u201c eine interessante Entdeckung. Er stellte eine enge Beziehung zwischen dem OBV-Indikator und der Fundamentalanalyse fest. Hierbei machte er eine grobe Einteilung des Aktienmarktes in Smart-Money und General Public. Konkret: Es geht um institutionelle Marktteilnehmer, die Insider-Wissen bez\u00fcglich der Unternehmen haben, und den restlichen Marktteilnehmern einen Schritt voraus sind. Seine Entdeckung war, dass der OBV vorauslaufend zu den fundamentalen Kennzahlen ist. Wer dem OBV folgt, der handelt in \u00dcbereinstimmung mit dem Smart-Money. Was wiederum Vorteile durch das Insider-Wissen des Smart-Moneys bringt. Der OBV-Trend (hier ein Synonym f\u00fcr den Volumentrend) zeigt, ob eine Aktie langfristig von den institutionellen Marktteilnehmern eingesammelt wird oder nicht.<\/p>\n<p>Es gibt nicht selten die Phasen eines Seitw\u00e4rtsmarktes. In dieser Zeit gibt es keine neuen Hochs oder Tiefs des OBVs. Es ist eine Zeit des Zweifelns. W\u00e4hrend dieser Phase sollte man nach neuen OBV-Ausbr\u00fcchen suchen. Sie sind oftmals die Vorboten f\u00fcr die zuk\u00fcnftige Kursrichtung, weil das Smart-Money sich in dem Wertpapier engagiert.<\/p>\n<h3>Ein praktisches Beispiel f\u00fcr die Analyse des Volumentrends<\/h3>\n<p>Die Umsetzung ist relativ einfach. Alles, was wir ben\u00f6tigen ist ein Kurs-Chart und ein Volumenindikator. In unserem Beispiel ist es der OBV.<\/p>\n<p><a href=\"https:\/\/www.trading-ideen.de\/wordpress\/wp-content\/uploads\/2017\/08\/b3.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6624\" src=\"https:\/\/www.trading-ideen.de\/wordpress\/wp-content\/uploads\/2017\/08\/b3-600x402.png\" alt=\"Vergleich Volumentrend u. Kurstrend\" width=\"600\" height=\"402\" srcset=\"https:\/\/www.trading-ideen.de\/wordpress\/wp-content\/uploads\/2017\/08\/b3-600x402.png 600w, https:\/\/www.trading-ideen.de\/wordpress\/wp-content\/uploads\/2017\/08\/b3-768x514.png 768w, https:\/\/www.trading-ideen.de\/wordpress\/wp-content\/uploads\/2017\/08\/b3-1024x686.png 1024w, https:\/\/www.trading-ideen.de\/wordpress\/wp-content\/uploads\/2017\/08\/b3.png 1296w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><em>Bild: Beispiel f\u00fcr die Analyse des Volumentrends mit dem OBV-Indikator<\/em><\/p>\n<p>Das obere Bild zeigt den TecDAX-Index mit seinem OBV. Eingef\u00fcgt wurde zus\u00e4tzlich ein einfacher gleitender Durchschnitt von 100 Perioden (GDL100). Die Periodenl\u00e4nge ist allerdings nicht wichtig. F\u00fcr die Analyse l\u00e4sst sich jede beliebige L\u00e4nge ausw\u00e4hlen. Wichtig w\u00e4re, dass die Periodenl\u00e4nge sowohl im Kurs-Chart als auch beim OBV-Indikator identisch ist.<\/p>\n<p>Zur Analyse kann man sich dann die GDL-\u00dcberschneidungen, sowohl beim Kursverlauf als beim OBV ansehen. Im Chart sind drei Beispiele grau markiert.<br \/>\nIn ersten Fall sieht man, dass der OBV dynamischer, im Vergleich zum Kurs-Chart, den GDL100 durchdringt. Der Kurs folgt etwas sp\u00e4ter dem Volumen. Das ist regelkonform, denn das Volumen l\u00e4uft dem Preis meisten voraus.<\/p>\n<p>Beim zweiten Beispiel haben wir wieder einen vorauslaufenden OBV. W\u00e4hrend der Kursverlauf unterhalb des GDL100 liegt, zeigt der OBV ein Paradebeispiel f\u00fcr eine bullishe Divergenz. Offensichtlich haben die Verk\u00e4ufer das Interesse verloren, und die Gro\u00dfverk\u00e4ufe eingestellt. Der Effekt ist bullish. Der OBV bleibt oberhalb seines GDL100.<\/p>\n<p>Das dritte Beispiel zeigt ein wenig die T\u00fccken der Technischen Analyse. Der OBV durchst\u00f6\u00dft mit einer kr\u00e4ftigen Bewegung die GDL100-Linie. Das wirkt auf den ersten Blick bearish. Der nachfolgende kurzfristige Verlauf bleibt dann bemerkenswert. Der OBV k\u00e4mpft sich n\u00e4mlich schnell wieder in das Gebiet oberhalb der GDL100. Ganz anders bewegt sich der Kursverlauf. Der Kurs bleibt kurzfristig unterhalb der GDL100. Der Effekt ist eine neue und schnelle bullishe Divergenz. Was zuvor bearish aussah, wird kurze Zeit sp\u00e4ter bullish.<\/p>\n<h3>Studieren Sie die Marktkr\u00e4fte<\/h3>\n<p>Eine gute Volumen-Analyse ist das Studium der Marktkr\u00e4fte. Welche Seite besitzt die gr\u00f6\u00dfte Zugkraft? Und an dieser Stelle muss der Trader den Mut zur Entscheidung haben, um mit der starken Seite mitzugehen. Es gibt kritische Punkte in jedem Trend. An diesen \u201eKeypoints\u201c scheint es so, als ob eine leichte Feder gen\u00fcgt, um den Kurs nach oben unten zu schicken. In den meisten F\u00e4llen orientiert sich der Markt nach dem Volumentrend. Ein Trader, der solche Keypoints fokussieren kann, hat viel zu gewinnen und wenig zu verlieren.<\/p>\n<p><strong>N\u00e4chster Artikel:<\/strong><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"gDfo55zhFB\"><p><a href=\"https:\/\/www.trading-ideen.de\/wordpress\/trading-mit-der-saisonalitaet\/\">Trading mit der Saisonalit\u00e4t<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8222;Trading mit der Saisonalit\u00e4t&#8220; &#8212; Trading-Ideen.de\" src=\"https:\/\/www.trading-ideen.de\/wordpress\/trading-mit-der-saisonalitaet\/embed\/#?secret=tS7X9nniih#?secret=gDfo55zhFB\" data-secret=\"gDfo55zhFB\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Der Volumentrend zeigt, ob ein Kurstrend gesund ist. Beide Trendvarianten m\u00fcssen im Einklang sein. Nur dann wird ein Trend von Dauer sein. Achten Sie deshalb auf den Volumentrend und Ihre Gewinne werden sich ausweiten. Vermutlich <a class=\"mh-excerpt-more\" href=\"https:\/\/www.trading-ideen.de\/wordpress\/volumentrend\/\" title=\"Ausbr\u00fcche mit dem Volumentrend handeln\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":6623,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[612],"class_list":{"0":"post-6621","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-know-how","8":"tag-volumentrend"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ausbr\u00fcche mit dem Volumentrend handeln - Trading-Ideen.de<\/title>\n<meta name=\"description\" content=\"Ausbr\u00fcche gelingen, wenn Kurs- und Volumentrend in Harmonie sind. \u2713 Vergleichen Sie die Kursbewegungen mit dem On-Balance-Volume \u2713 Top Trading -Gewinne\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.trading-ideen.de\/wordpress\/volumentrend\/\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/volumentrend\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/volumentrend\\\/\"},\"author\":{\"name\":\"Christian\",\"@id\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/1fa94ccf90a4cf02950096a07c88d4dd\"},\"headline\":\"Ausbr\u00fcche mit dem Volumentrend handeln\",\"datePublished\":\"2017-08-29T20:12:58+00:00\",\"dateModified\":\"2022-07-20T14:58:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/volumentrend\\\/\"},\"wordCount\":1225,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/volumentrend\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/b2.jpg\",\"keywords\":[\"Volumentrend\"],\"articleSection\":[\"Wissen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/volumentrend\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/volumentrend\\\/\",\"url\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/volumentrend\\\/\",\"name\":\"Ausbr\u00fcche mit dem Volumentrend handeln - Trading-Ideen.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/volumentrend\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/volumentrend\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/b2.jpg\",\"datePublished\":\"2017-08-29T20:12:58+00:00\",\"dateModified\":\"2022-07-20T14:58:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/1fa94ccf90a4cf02950096a07c88d4dd\"},\"description\":\"Ausbr\u00fcche gelingen, wenn Kurs- und Volumentrend in Harmonie sind. \u2713 Vergleichen Sie die Kursbewegungen mit dem On-Balance-Volume \u2713 Top Trading -Gewinne\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/volumentrend\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/volumentrend\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/volumentrend\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/b2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/b2.jpg\",\"width\":545,\"height\":356},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/volumentrend\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ausbr\u00fcche mit dem Volumentrend handeln\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/\",\"name\":\"Trading-Ideen.de\",\"description\":\"Tipps und Gedanken zur B\u00f6rse\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/1fa94ccf90a4cf02950096a07c88d4dd\",\"name\":\"Christian\",\"url\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/author\\\/c-lukas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ausbr\u00fcche mit dem Volumentrend handeln - Trading-Ideen.de","description":"Ausbr\u00fcche gelingen, wenn Kurs- und Volumentrend in Harmonie sind. \u2713 Vergleichen Sie die Kursbewegungen mit dem On-Balance-Volume \u2713 Top Trading -Gewinne","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.trading-ideen.de\/wordpress\/volumentrend\/","twitter_misc":{"Verfasst von":"Christian","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.trading-ideen.de\/wordpress\/volumentrend\/#article","isPartOf":{"@id":"https:\/\/www.trading-ideen.de\/wordpress\/volumentrend\/"},"author":{"name":"Christian","@id":"https:\/\/www.trading-ideen.de\/wordpress\/#\/schema\/person\/1fa94ccf90a4cf02950096a07c88d4dd"},"headline":"Ausbr\u00fcche mit dem Volumentrend handeln","datePublished":"2017-08-29T20:12:58+00:00","dateModified":"2022-07-20T14:58:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.trading-ideen.de\/wordpress\/volumentrend\/"},"wordCount":1225,"commentCount":0,"image":{"@id":"https:\/\/www.trading-ideen.de\/wordpress\/volumentrend\/#primaryimage"},"thumbnailUrl":"https:\/\/www.trading-ideen.de\/wordpress\/wp-content\/uploads\/2017\/08\/b2.jpg","keywords":["Volumentrend"],"articleSection":["Wissen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.trading-ideen.de\/wordpress\/volumentrend\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.trading-ideen.de\/wordpress\/volumentrend\/","url":"https:\/\/www.trading-ideen.de\/wordpress\/volumentrend\/","name":"Ausbr\u00fcche mit dem Volumentrend handeln - Trading-Ideen.de","isPartOf":{"@id":"https:\/\/www.trading-ideen.de\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.trading-ideen.de\/wordpress\/volumentrend\/#primaryimage"},"image":{"@id":"https:\/\/www.trading-ideen.de\/wordpress\/volumentrend\/#primaryimage"},"thumbnailUrl":"https:\/\/www.trading-ideen.de\/wordpress\/wp-content\/uploads\/2017\/08\/b2.jpg","datePublished":"2017-08-29T20:12:58+00:00","dateModified":"2022-07-20T14:58:22+00:00","author":{"@id":"https:\/\/www.trading-ideen.de\/wordpress\/#\/schema\/person\/1fa94ccf90a4cf02950096a07c88d4dd"},"description":"Ausbr\u00fcche gelingen, wenn Kurs- und Volumentrend in Harmonie sind. \u2713 Vergleichen Sie die Kursbewegungen mit dem On-Balance-Volume \u2713 Top Trading -Gewinne","breadcrumb":{"@id":"https:\/\/www.trading-ideen.de\/wordpress\/volumentrend\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.trading-ideen.de\/wordpress\/volumentrend\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.trading-ideen.de\/wordpress\/volumentrend\/#primaryimage","url":"https:\/\/www.trading-ideen.de\/wordpress\/wp-content\/uploads\/2017\/08\/b2.jpg","contentUrl":"https:\/\/www.trading-ideen.de\/wordpress\/wp-content\/uploads\/2017\/08\/b2.jpg","width":545,"height":356},{"@type":"BreadcrumbList","@id":"https:\/\/www.trading-ideen.de\/wordpress\/volumentrend\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.trading-ideen.de\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Ausbr\u00fcche mit dem Volumentrend handeln"}]},{"@type":"WebSite","@id":"https:\/\/www.trading-ideen.de\/wordpress\/#website","url":"https:\/\/www.trading-ideen.de\/wordpress\/","name":"Trading-Ideen.de","description":"Tipps und Gedanken zur B\u00f6rse","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.trading-ideen.de\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.trading-ideen.de\/wordpress\/#\/schema\/person\/1fa94ccf90a4cf02950096a07c88d4dd","name":"Christian","url":"https:\/\/www.trading-ideen.de\/wordpress\/author\/c-lukas\/"}]}},"_links":{"self":[{"href":"https:\/\/www.trading-ideen.de\/wordpress\/wp-json\/wp\/v2\/posts\/6621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trading-ideen.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.trading-ideen.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.trading-ideen.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.trading-ideen.de\/wordpress\/wp-json\/wp\/v2\/comments?post=6621"}],"version-history":[{"count":6,"href":"https:\/\/www.trading-ideen.de\/wordpress\/wp-json\/wp\/v2\/posts\/6621\/revisions"}],"predecessor-version":[{"id":11245,"href":"https:\/\/www.trading-ideen.de\/wordpress\/wp-json\/wp\/v2\/posts\/6621\/revisions\/11245"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.trading-ideen.de\/wordpress\/wp-json\/wp\/v2\/media\/6623"}],"wp:attachment":[{"href":"https:\/\/www.trading-ideen.de\/wordpress\/wp-json\/wp\/v2\/media?parent=6621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.trading-ideen.de\/wordpress\/wp-json\/wp\/v2\/categories?post=6621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.trading-ideen.de\/wordpress\/wp-json\/wp\/v2\/tags?post=6621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}