{"id":8120,"date":"2018-08-20T08:46:45","date_gmt":"2018-08-20T06:46:45","guid":{"rendered":"http:\/\/www.trading-ideen.de\/wordpress\/?p=8120"},"modified":"2018-08-21T17:50:31","modified_gmt":"2018-08-21T15:50:31","slug":"edge-trading-aktien-mit-statistischem-vorteil-kw-34-2018","status":"publish","type":"post","link":"https:\/\/www.trading-ideen.de\/wordpress\/edge-trading-aktien-mit-statistischem-vorteil-kw-34-2018\/","title":{"rendered":"Edge-Trading: Aktien mit statistischem Vorteil | KW 34 2018"},"content":{"rendered":"<p>Einen wundersch\u00f6nen guten Tag liebe Statistic-Trader und Traderinnen,<\/p>\n<p>auch diese Woche haben wir Edge-Aktien f\u00fcr Sie analysiert und vorbereitet.<\/p>\n<p>Falls Sie das Edge-Trading-Format noch nicht kennen, dann k\u00f6nnen Sie sich die Regeln und die Idee dahinter hier durchlesen:\u00a0<strong><a href=\"http:\/\/www.statistic-trading.de\/edge-trading-kw-48-2016\/\">Edge-Trading-Informationen<\/a><\/strong>.<\/p>\n<p>Wer sich mit der Systematik der Edge-Aktien bekannt machen will, der sollte sich unsere Artikel-Reihe:\u00a0<strong><em><a href=\"http:\/\/www.statistic-trading.de\/statistische-markttechnik-trading\/\">Statistische Markttechnik\u00a0<\/a><\/em><\/strong>genauestens durchlesen. Dort werden die Statistiken und die Logik hinter den Edge-Aktien offengelegt und erkl\u00e4rt.<\/p>\n<p>Nun hat sich aber etwas f\u00fcr uns getan. Mit Hilfe des Metatrader 5 k\u00f6nnen wir nun all unsere Aktien mit Hilfe unseres\u00a0<a href=\"http:\/\/www.statistic-trading.de\/produkt\/markttechnischer-trenderkennungs-algorithmus\/\">Markttechnischen Trenderkennungs-Algorithmus\u00a0<\/a>scannen und m\u00fcssen dieses nicht mehr \u00fcber freestockcharts.com tun.<\/p>\n<p>Wir k\u00f6nnen nun auch deutsche Aktien zu unserem Trading hinzuziehen.<\/p>\n<p>Das erm\u00f6glicht uns ein neues Spektrum an Aktien und Trading-M\u00f6glichkeiten.<\/p>\n<p>Kommen wir nun zu unseren Edge-Aktien der vorherigen Woche.<\/p>\n<h2>Edge-Aktie: Citygroup Inc (Abk\u00fcrzung: C | Trendrichtung: Long)<\/h2>\n<h6 style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5487\" src=\"https:\/\/www.statistic-trading.de\/wp-content\/uploads\/2018\/08\/Citygroup-Inc-C-LONG.png\" alt=\"\" width=\"1966\" height=\"924\" \/><em>(Abbildung aus der vorherigen Woche Metatrader 5)<\/em><\/h6>\n<h6 style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5509\" src=\"https:\/\/www.statistic-trading.de\/wp-content\/uploads\/2018\/08\/C-TRENDBRUCH.png\" alt=\"\" width=\"1966\" height=\"982\" \/><em>(Abbildung aus der jetzigen Woche Metatrader 5)<\/em><\/h6>\n<p>&nbsp;<\/p>\n<p>Die Citygroup Aktie konnte in der vergangenen Handelswoche einen Trendbruch hinlegen.<\/p>\n<p>Die Aktie ist an jedem Tag, ohne auch nur ein Anzeichen einer Erholung, bis in die Trendbruchs-Phase gefallen und hat somit unseren Edge verweigert.<\/p>\n<p>Somit ist die Citygroup Aktie erstmal nicht mehr interessant f\u00fcr uns.<\/p>\n<p>&nbsp;<\/p>\n<h2>Edge-Aktie: General Motors (Abk\u00fcrzung: GM | Trendrichtung: Short)<\/h2>\n<h6 style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5489\" src=\"https:\/\/www.statistic-trading.de\/wp-content\/uploads\/2018\/08\/General-Motors-GM-Short.png\" alt=\"\" width=\"1962\" height=\"926\" \/><em>(Abbildung aus der vorherigen Woche Metatrader 5)<\/em><\/h6>\n<h6 style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5511\" src=\"https:\/\/www.statistic-trading.de\/wp-content\/uploads\/2018\/08\/GM-EDGE.png\" alt=\"\" width=\"1966\" height=\"982\" \/><em>(Abbildung aus der jetzigen Woche Metatrader 5)<\/em><\/h6>\n<p>&nbsp;<\/p>\n<p>W\u00e4hrend die Citygroup uns ein \u201enegatives\u201c Ergebnis gebracht hat, so konnte General Motors uns ein \u201epositives\u201c Ergebnis abliefern.<\/p>\n<p>Die General Motors Aktie hat unser Edge-Niveau erreicht und konnte auch noch weiter dr\u00fcber hinausfallen.<\/p>\n<p>Nun entscheiden Sie mit Ihrem pers\u00f6nlichen Risk-Management ob Sie diese Aktie noch weiter im Depot halten wollen oder nicht.<\/p>\n<p>&nbsp;<\/p>\n<h2>Edge-Aktie: Walt Disney Co (Abk\u00fcrzung: DIS | Trendrichtung: Long)<\/h2>\n<h6 style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5491\" src=\"https:\/\/www.statistic-trading.de\/wp-content\/uploads\/2018\/08\/Walt-Disney-Co-DIS-LONG.png\" alt=\"\" width=\"1968\" height=\"926\" \/><em>(Abbildung aus der vorherigen Woche Metatrader 5)<\/em><\/h6>\n<h6 style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5513\" src=\"https:\/\/www.statistic-trading.de\/wp-content\/uploads\/2018\/08\/DIS-02.png\" alt=\"\" width=\"1972\" height=\"982\" \/><em>(Abbildung aus der jetzigen Woche Metatrader 5)<\/em><\/h6>\n<p>&nbsp;<\/p>\n<p>In der Disney-Aktie hat sich in der vergangenen Handelswoche nicht viel getan.<\/p>\n<p>Die Korrektur konnte sich zwar ein wenig \u201everst\u00e4rken\u201c, aber es kam auch zu kleineren Gegenbewegungen in Richtung Edge.<\/p>\n<p>Die kommende Handelswoche wird zeigen, wie sich die Disney-Aktie entwickeln wird.<\/p>\n<p>&nbsp;<\/p>\n<p>Schauen wir uns nun die Edge-Aktien f\u00fcr die kommende Handelswoche an:<\/p>\n<p>&nbsp;<\/p>\n<h2>Edge-Aktie Nr.1: Deutsche Telekom AG (Abk\u00fcrzung: DTE | Trendrichtung: Long)<\/h2>\n<h6 style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5515\" src=\"https:\/\/www.statistic-trading.de\/wp-content\/uploads\/2018\/08\/Deutsche-Telekom-Ag-DTE-LONG.png\" alt=\"\" width=\"1968\" height=\"980\" \/><em>(Abbildung: Metatrader 5)<\/em><\/h6>\n<p>&nbsp;<\/p>\n<p>Unsere erste Edge-Aktie f\u00fcr die kommende Trading-Woche ist: Deutsche Telekom.<\/p>\n<p>Der MTA hat erkannt, dass sich die Deutsche Telekom in einem wirklich guten Aufw\u00e4rtstrend befindet, von diesem wir nun profitieren wollen.<\/p>\n<p>Korrigiert nun die Telekom bis zu einem Preisniveau von 13.56\u20ac, so w\u00fcrde es zu einem Trendbruch kommen und die Telekom-Aktie w\u00e4re nicht mehr interessant f\u00fcr uns.<\/p>\n<p>Steigt die Aktie jedoch, wie erwartet, und erreicht 14.40\u20ac, so w\u00fcrde unser Edge aufgehen und die Telekom-Aktie h\u00e4tte, eventuell, noch weiteres Potenzial zu steigen.<\/p>\n<p>&nbsp;<\/p>\n<h2>Edge-Aktie Nr.2: Ebay Inc (Abk\u00fcrzung: EBAY | Trendrichtung: Short)<\/h2>\n<h6 style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5517\" src=\"https:\/\/www.statistic-trading.de\/wp-content\/uploads\/2018\/08\/Ebay-Inc-EBAY-Short.png\" alt=\"\" width=\"1968\" height=\"978\" \/><em>(Abbildung: Metatrader 5)<\/em><\/h6>\n<p>&nbsp;<\/p>\n<p>Unsere zweite Edge-Aktie f\u00fcr die kommende Handelswoche ist: Ebay.<\/p>\n<p>Die Ebay-Aktie war schon fast am Edge-Bruch Niveau und konnte dieses aber noch halten.<\/p>\n<p>Vergessen wir nicht die Tatsache, dass je st\u00e4rker eine Aktie sich dem Trendbruch n\u00e4hert, umso h\u00f6her wird die Wahrscheinlichkeit, dass ein Trendbruch auch tats\u00e4chlich stattfindet. Somit ist eine Anpassung des Risk-Management empfohlen.<\/p>\n<p>Korrigiert somit die Ebay-Aktie weiter und erreicht 34.90$, so w\u00fcrde es in der Ebay-Aktie zu einem Trendbruch kommen.<\/p>\n<p>F\u00e4llt die Aktie jedoch und erreicht 33.05$, so w\u00fcrde unser Edge aufgehen und eventuell k\u00f6nnte die Ebay-Aktie noch weiter abfallen.<\/p>\n<p>&nbsp;<\/p>\n<h2>Edge-Aktie Nr.3: Travelers Companies Inc (Abk\u00fcrzung: TRV | Trendrichtung: Long)<\/h2>\n<h6 style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5519\" src=\"https:\/\/www.statistic-trading.de\/wp-content\/uploads\/2018\/08\/Travelers-Companies-Inc-TRV-LONG.png\" alt=\"\" width=\"1968\" height=\"980\" \/><em>(Abbildung: Metatrader 5)<\/em><\/h6>\n<p>&nbsp;<\/p>\n<p>Unsere dritte und letzte Edge-Aktie ist die Travelers Companies Inc.<\/p>\n<p>Auch in dieser Edge-Aktie m\u00f6chten wir nun von einem Aufw\u00e4rtstrend unser St\u00fcckchen abhaben.<\/p>\n<p>Korrigiert somit die Travelers bis auf 123.10$, so w\u00fcrde es zu einem Trendbruch kommen und die Travelers w\u00e4re nicht mehr interessant f\u00fcr unseren Edge.<\/p>\n<p>Steigt die Aktie jedoch und erreicht 132.40$, so w\u00fcrde die Travelers unseren Edge erreichen und auch hier w\u00fcrden wir, eventuell, noch weiteren Potenzial nach oben sehen.<\/p>\n<p>&nbsp;<\/p>\n<h2>Neues Feature: Korrelations-Matrix<\/h2>\n<p>Wir von Statistic-Trading m\u00f6chten Ihnen mit diesem neuen Feature nun noch mehr Informationen \u00fcber die Edge-Aktien zur Verf\u00fcgung stellen.<\/p>\n<p>Somit wird es ab heute in jeder Edge-Ausgabe zu den aktuell aktiven US-Edge-Aktien eine Korrelations-Matrix geben, damit Sie Ihr Risk-Management besser anpassen k\u00f6nnen.<\/p>\n<p>In unserem Hinweis deuten wir ja immer darauf hin, dass Sie sich bitte die Korrelationen anschauen sollen um nicht ein doppeltes Risiko in zwei korrelierenden Aktien zu haben.<\/p>\n<p>Die Korrelations-Matrix wird Ihnen nun dieses erleichtern.<\/p>\n<p>F\u00fcr die Berechnung der Korrelations-Matrix nehmen wir eine Historie von 3-Jahren auf Tages-Basis.<\/p>\n<p>Es ist aber so, dass wir aktuell nur die Korrelationen f\u00fcr die US-Aktien Ihnen zur Verf\u00fcgung stellen k\u00f6nnen. F\u00fcr die US-Aktien haben wir eine wunderbare und fehlerfreie Datenbasis und k\u00f6nnen somit sichergehen, dass die Korrelationen richtig berechnet worden sind.<\/p>\n<p>F\u00fcr Deutsche-Aktien haben wir keine so sauberen Daten und m\u00f6chten somit hier sagen, dass es nur Korrelationen f\u00fcr aktive US-Edge-Aktien geben wird und leider nicht f\u00fcr deutsche Aktien.<\/p>\n<p>Nun, wie schon angesagt, die aktuelle Korrelations-Matrix:<\/p>\n<h6 style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5521\" src=\"https:\/\/www.statistic-trading.de\/wp-content\/uploads\/2018\/08\/Korrelations-Matrix-KW-34.png\" alt=\"\" width=\"1706\" height=\"986\" \/>(Abbildung: Korrelations-Matrix KW 34)<\/h6>\n<p>&nbsp;<\/p>\n<p>Somit passen Sie Ihr Risk-Management nun mit diesem Wissen an und riskieren Sie nicht zu viel Kapital in zu stark korrelierende M\u00e4rkte.<\/p>\n<p>Wir werden die Korrelations-Matrix Woche f\u00fcr Woche mit den aktuellen Edge-Aktien erg\u00e4nzen oder die inaktiven herausnehmen.<\/p>\n<p>Hiermit sollen Sie einen noch besseren statistischen \u00dcberblick \u00fcber die Edge-Aktien erhalten.<\/p>\n<p>Wir hoffen wir k\u00f6nnen Ihnen mit der Korrelations-Matrix in Ihrem Trading weiterhelfen.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"entry-content\">\n<p><strong>WICHTIGE ANMERKUNG:<\/strong><\/p>\n<p><strong>Bitte achten Sie auf m\u00f6gliche Korrelationen zum Index und auch m\u00f6gliche Korrelationen der Aktien untereinander, so dass Sie nicht zu hohes Risiko fahren und Aktien mit \u00e4hnlicher Korrelation mit einer gleichen Positionsgr\u00f6\u00dfe traden.<\/strong><\/p>\n<p><strong>Bitte machen Sie sich die Arbeit und \u00fcberpr\u00fcfen sorgf\u00e4ltig Ihre Positionen. Sie w\u00fcrden ja auch nicht mit Ihrem Auto ein Rennen fahren ohne zu pr\u00fcfen, dass Sie genug Benzin, Bremsfl\u00fcssigkeit und andere wichtige Faktoren positiv erf\u00fcllt werden.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<div class=\"entry-content\">\n<p>Mit freundlichen Gr\u00fc\u00dfen aus der Hauptstadt,<\/p>\n<p>Statistic-Trading<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Einen wundersch\u00f6nen guten Tag liebe Statistic-Trader und Traderinnen, auch diese Woche haben wir Edge-Aktien f\u00fcr Sie analysiert und vorbereitet. Falls Sie das Edge-Trading-Format noch nicht kennen, dann k\u00f6nnen Sie sich die Regeln und die Idee <a class=\"mh-excerpt-more\" href=\"https:\/\/www.trading-ideen.de\/wordpress\/edge-trading-aktien-mit-statistischem-vorteil-kw-34-2018\/\" title=\"Edge-Trading: Aktien mit statistischem Vorteil | KW 34 2018\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":6,"featured_media":4100,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[372],"tags":[],"class_list":{"0":"post-8120","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-statistik-trader"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Edge-Trading: Aktien mit statistischem Vorteil | KW 34 2018 - Trading-Ideen.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.trading-ideen.de\/wordpress\/edge-trading-aktien-mit-statistischem-vorteil-kw-34-2018\/\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juri\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/edge-trading-aktien-mit-statistischem-vorteil-kw-34-2018\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/edge-trading-aktien-mit-statistischem-vorteil-kw-34-2018\\\/\"},\"author\":{\"name\":\"Juri\",\"@id\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/fdc7dcb13a8e13d5cee8b77bebff5045\"},\"headline\":\"Edge-Trading: Aktien mit statistischem Vorteil | KW 34 2018\",\"datePublished\":\"2018-08-20T06:46:45+00:00\",\"dateModified\":\"2018-08-21T15:50:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/edge-trading-aktien-mit-statistischem-vorteil-kw-34-2018\\\/\"},\"wordCount\":1022,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/edge-trading-aktien-mit-statistischem-vorteil-kw-34-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/Beitrag-Statistik-Trader.png\",\"articleSection\":[\"Statistik-Trader\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/edge-trading-aktien-mit-statistischem-vorteil-kw-34-2018\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/edge-trading-aktien-mit-statistischem-vorteil-kw-34-2018\\\/\",\"url\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/edge-trading-aktien-mit-statistischem-vorteil-kw-34-2018\\\/\",\"name\":\"Edge-Trading: Aktien mit statistischem Vorteil | KW 34 2018 - Trading-Ideen.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/edge-trading-aktien-mit-statistischem-vorteil-kw-34-2018\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/edge-trading-aktien-mit-statistischem-vorteil-kw-34-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/Beitrag-Statistik-Trader.png\",\"datePublished\":\"2018-08-20T06:46:45+00:00\",\"dateModified\":\"2018-08-21T15:50:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/fdc7dcb13a8e13d5cee8b77bebff5045\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/edge-trading-aktien-mit-statistischem-vorteil-kw-34-2018\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/edge-trading-aktien-mit-statistischem-vorteil-kw-34-2018\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/edge-trading-aktien-mit-statistischem-vorteil-kw-34-2018\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/Beitrag-Statistik-Trader.png\",\"contentUrl\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/Beitrag-Statistik-Trader.png\",\"width\":332,\"height\":57,\"caption\":\"Statistik-Trader\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/edge-trading-aktien-mit-statistischem-vorteil-kw-34-2018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Edge-Trading: Aktien mit statistischem Vorteil | KW 34 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/\",\"name\":\"Trading-Ideen.de\",\"description\":\"Tipps und Gedanken zur B\u00f6rse\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/fdc7dcb13a8e13d5cee8b77bebff5045\",\"name\":\"Juri\",\"sameAs\":[\"http:\\\/\\\/wwww.statistic-trading.de\"],\"url\":\"https:\\\/\\\/www.trading-ideen.de\\\/wordpress\\\/author\\\/juri\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Edge-Trading: Aktien mit statistischem Vorteil | KW 34 2018 - Trading-Ideen.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.trading-ideen.de\/wordpress\/edge-trading-aktien-mit-statistischem-vorteil-kw-34-2018\/","twitter_misc":{"Verfasst von":"Juri","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.trading-ideen.de\/wordpress\/edge-trading-aktien-mit-statistischem-vorteil-kw-34-2018\/#article","isPartOf":{"@id":"https:\/\/www.trading-ideen.de\/wordpress\/edge-trading-aktien-mit-statistischem-vorteil-kw-34-2018\/"},"author":{"name":"Juri","@id":"https:\/\/www.trading-ideen.de\/wordpress\/#\/schema\/person\/fdc7dcb13a8e13d5cee8b77bebff5045"},"headline":"Edge-Trading: Aktien mit statistischem Vorteil | KW 34 2018","datePublished":"2018-08-20T06:46:45+00:00","dateModified":"2018-08-21T15:50:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.trading-ideen.de\/wordpress\/edge-trading-aktien-mit-statistischem-vorteil-kw-34-2018\/"},"wordCount":1022,"commentCount":0,"image":{"@id":"https:\/\/www.trading-ideen.de\/wordpress\/edge-trading-aktien-mit-statistischem-vorteil-kw-34-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/www.trading-ideen.de\/wordpress\/wp-content\/uploads\/2016\/10\/Beitrag-Statistik-Trader.png","articleSection":["Statistik-Trader"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.trading-ideen.de\/wordpress\/edge-trading-aktien-mit-statistischem-vorteil-kw-34-2018\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.trading-ideen.de\/wordpress\/edge-trading-aktien-mit-statistischem-vorteil-kw-34-2018\/","url":"https:\/\/www.trading-ideen.de\/wordpress\/edge-trading-aktien-mit-statistischem-vorteil-kw-34-2018\/","name":"Edge-Trading: Aktien mit statistischem Vorteil | KW 34 2018 - Trading-Ideen.de","isPartOf":{"@id":"https:\/\/www.trading-ideen.de\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.trading-ideen.de\/wordpress\/edge-trading-aktien-mit-statistischem-vorteil-kw-34-2018\/#primaryimage"},"image":{"@id":"https:\/\/www.trading-ideen.de\/wordpress\/edge-trading-aktien-mit-statistischem-vorteil-kw-34-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/www.trading-ideen.de\/wordpress\/wp-content\/uploads\/2016\/10\/Beitrag-Statistik-Trader.png","datePublished":"2018-08-20T06:46:45+00:00","dateModified":"2018-08-21T15:50:31+00:00","author":{"@id":"https:\/\/www.trading-ideen.de\/wordpress\/#\/schema\/person\/fdc7dcb13a8e13d5cee8b77bebff5045"},"breadcrumb":{"@id":"https:\/\/www.trading-ideen.de\/wordpress\/edge-trading-aktien-mit-statistischem-vorteil-kw-34-2018\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.trading-ideen.de\/wordpress\/edge-trading-aktien-mit-statistischem-vorteil-kw-34-2018\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.trading-ideen.de\/wordpress\/edge-trading-aktien-mit-statistischem-vorteil-kw-34-2018\/#primaryimage","url":"https:\/\/www.trading-ideen.de\/wordpress\/wp-content\/uploads\/2016\/10\/Beitrag-Statistik-Trader.png","contentUrl":"https:\/\/www.trading-ideen.de\/wordpress\/wp-content\/uploads\/2016\/10\/Beitrag-Statistik-Trader.png","width":332,"height":57,"caption":"Statistik-Trader"},{"@type":"BreadcrumbList","@id":"https:\/\/www.trading-ideen.de\/wordpress\/edge-trading-aktien-mit-statistischem-vorteil-kw-34-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.trading-ideen.de\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Edge-Trading: Aktien mit statistischem Vorteil | KW 34 2018"}]},{"@type":"WebSite","@id":"https:\/\/www.trading-ideen.de\/wordpress\/#website","url":"https:\/\/www.trading-ideen.de\/wordpress\/","name":"Trading-Ideen.de","description":"Tipps und Gedanken zur B\u00f6rse","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.trading-ideen.de\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.trading-ideen.de\/wordpress\/#\/schema\/person\/fdc7dcb13a8e13d5cee8b77bebff5045","name":"Juri","sameAs":["http:\/\/wwww.statistic-trading.de"],"url":"https:\/\/www.trading-ideen.de\/wordpress\/author\/juri\/"}]}},"_links":{"self":[{"href":"https:\/\/www.trading-ideen.de\/wordpress\/wp-json\/wp\/v2\/posts\/8120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trading-ideen.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.trading-ideen.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.trading-ideen.de\/wordpress\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.trading-ideen.de\/wordpress\/wp-json\/wp\/v2\/comments?post=8120"}],"version-history":[{"count":2,"href":"https:\/\/www.trading-ideen.de\/wordpress\/wp-json\/wp\/v2\/posts\/8120\/revisions"}],"predecessor-version":[{"id":8133,"href":"https:\/\/www.trading-ideen.de\/wordpress\/wp-json\/wp\/v2\/posts\/8120\/revisions\/8133"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.trading-ideen.de\/wordpress\/wp-json\/wp\/v2\/media\/4100"}],"wp:attachment":[{"href":"https:\/\/www.trading-ideen.de\/wordpress\/wp-json\/wp\/v2\/media?parent=8120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.trading-ideen.de\/wordpress\/wp-json\/wp\/v2\/categories?post=8120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.trading-ideen.de\/wordpress\/wp-json\/wp\/v2\/tags?post=8120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}